{"id":1098,"date":"2025-03-15T02:15:34","date_gmt":"2025-03-15T01:15:34","guid":{"rendered":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/?post_type=amenidad&#038;p=1098"},"modified":"2025-05-02T13:12:22","modified_gmt":"2025-05-02T19:12:22","slug":"garita-de-acceso","status":"publish","type":"amenidad","link":"https:\/\/hogaresisn.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/","title":{"rendered":"Garita de Acceso"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1098\" class=\"elementor elementor-1098\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2522a6ab e-flex e-con-boxed e-con e-parent\" data-id=\"2522a6ab\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75a8af0 elementor-widget elementor-widget-text-editor\" data-id=\"75a8af0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\"><p>Ubicada en el ingreso principal del conjunto residencial, equipada con sistemas modernos de vigilancia y control de acceso. Su funci\u00f3n principal es garantizar la privacidad y tranquilidad de todos los residentes, permitiendo solo la entrada de personas autorizadas y proporcionando un ambiente tranquilo y protegido.<\/p><figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2539b59 e-flex e-con-boxed e-con e-parent\" data-id=\"2539b59\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6b86ef elementor-widget elementor-widget-gva-heading-block\" data-id=\"a6b86ef\" data-element_type=\"widget\" data-widget_type=\"gva-heading-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gva-element-gva-heading-block gva-element\">\r\n   <div class=\"align-left style-2 widget gsc-heading box-align-left auto-responsive\">\r\n      \r\n      <div class=\"content-inner\">\r\n                  \r\n           \r\n         \r\n                     <h2 class=\"title\">\r\n               <span>Galer\u00eda<\/span>\r\n            <\/h2>\r\n                  \r\n         \r\n               <\/div>\r\n\r\n   <\/div>\r\n\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4549e3e elementor-widget elementor-widget-gva-gallery\" data-id=\"4549e3e\" data-element_type=\"widget\" data-widget_type=\"gva-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"gva-element-gva-gallery gva-element\">  \r\n  \t<div class=\"gva-gallery-grid clearfix \">\r\n\t\t<div class=\"gva-content-items\"> \r\n\t\t  \t<div class=\"lg-block-grid-3 md-block-grid-3 sm-block-grid-2 xs-block-grid-1 xx-block-grid-1\">\r\n\t\t\t \t<div class=\"item\"> \r\n   <div class=\"gallery-two__single\">\r\n               <div class=\"gallery-two__image\">\r\n            <img decoding=\"async\" src=\"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/amenidades-garita-1-600x540.jpg\" alt=\"Garita\" \/>  \r\n         <\/div>\r\n         <a class=\"gallery-two__photo\" href=\"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/amenidades-garita-1.jpg\" data-elementor-lightbox-slideshow=\"gallery-m132\"><\/a>\r\n         <\/div>\r\n <\/div><div class=\"item\"> \r\n   <div class=\"gallery-two__single\">\r\n               <div class=\"gallery-two__image\">\r\n            <img decoding=\"async\" src=\"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/amenidades-garita-2-600x540.jpg\" alt=\"Garita\" \/>  \r\n         <\/div>\r\n         <a class=\"gallery-two__photo\" href=\"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/amenidades-garita-2.jpg\" data-elementor-lightbox-slideshow=\"gallery-m132\"><\/a>\r\n         <\/div>\r\n <\/div><div class=\"item\"> \r\n   <div class=\"gallery-two__single\">\r\n               <div class=\"gallery-two__image\">\r\n            <img decoding=\"async\" src=\"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/amenidades-garita-3-600x540.jpg\" alt=\"Garita\" \/>  \r\n         <\/div>\r\n         <a class=\"gallery-two__photo\" href=\"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/amenidades-garita-3.jpg\" data-elementor-lightbox-slideshow=\"gallery-m132\"><\/a>\r\n         <\/div>\r\n <\/div>\t\t  \t<\/div>\r\n\t\t<\/div>\r\n  \t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\t\t<\/div>\n\t\t","protected":false},"featured_media":1099,"menu_order":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-1098","amenidad","type-amenidad","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v25.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Garita de Acceso - Paseo del Encinal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Garita de Acceso\" \/>\n<meta property=\"og:description\" content=\"Ubicada en el ingreso principal del conjunto residencial, equipada con sistemas modernos de vigilancia y control de acceso. Su funci\u00f3n principal es garantizar la privacidad y tranquilidad de todos los residentes, permitiendo solo la entrada de personas autorizadas y proporcionando un ambiente tranquilo y protegido. Galer\u00eda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/\" \/>\n<meta property=\"og:site_name\" content=\"Paseo del Encinal\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-02T19:12:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/garita-de-acceso-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/\",\"url\":\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/\",\"name\":\"Garita de Acceso - Paseo del Encinal\",\"isPartOf\":{\"@id\":\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/garita-de-acceso-scaled.jpg\",\"datePublished\":\"2025-03-15T01:15:34+00:00\",\"dateModified\":\"2025-05-02T19:12:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/#primaryimage\",\"url\":\"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/garita-de-acceso-scaled.jpg\",\"contentUrl\":\"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/garita-de-acceso-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hogaresisn.com\/paseo-del-encinal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Garita de Acceso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/#website\",\"url\":\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/\",\"name\":\"Paseo del Encinal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Garita de Acceso - Paseo del Encinal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/","og_locale":"es_ES","og_type":"article","og_title":"Garita de Acceso","og_description":"Ubicada en el ingreso principal del conjunto residencial, equipada con sistemas modernos de vigilancia y control de acceso. Su funci\u00f3n principal es garantizar la privacidad y tranquilidad de todos los residentes, permitiendo solo la entrada de personas autorizadas y proporcionando un ambiente tranquilo y protegido. Galer\u00eda","og_url":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/","og_site_name":"Paseo del Encinal","article_modified_time":"2025-05-02T19:12:22+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/garita-de-acceso-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/","url":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/","name":"Garita de Acceso - Paseo del Encinal","isPartOf":{"@id":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/#primaryimage"},"image":{"@id":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/#primaryimage"},"thumbnailUrl":"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/garita-de-acceso-scaled.jpg","datePublished":"2025-03-15T01:15:34+00:00","dateModified":"2025-05-02T19:12:22+00:00","breadcrumb":{"@id":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/#primaryimage","url":"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/garita-de-acceso-scaled.jpg","contentUrl":"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-content\/uploads\/sites\/3\/2025\/03\/garita-de-acceso-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/amenidades\/garita-de-acceso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hogaresisn.com\/paseo-del-encinal\/"},{"@type":"ListItem","position":2,"name":"Garita de Acceso"}]},{"@type":"WebSite","@id":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/#website","url":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/","name":"Paseo del Encinal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hogaresisn.xoratom.com\/paseo-del-encinal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-json\/wp\/v2\/amenidades\/1098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-json\/wp\/v2\/amenidades"}],"about":[{"href":"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-json\/wp\/v2\/types\/amenidad"}],"version-history":[{"count":61,"href":"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-json\/wp\/v2\/amenidades\/1098\/revisions"}],"predecessor-version":[{"id":2127,"href":"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-json\/wp\/v2\/amenidades\/1098\/revisions\/2127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-json\/wp\/v2\/media\/1099"}],"wp:attachment":[{"href":"https:\/\/hogaresisn.com\/paseo-del-encinal\/wp-json\/wp\/v2\/media?parent=1098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}